{"id":366,"date":"2020-08-27T18:27:56","date_gmt":"2020-08-27T21:27:56","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=ultimos_porgramas_po&#038;p=366"},"modified":"2020-08-27T18:27:56","modified_gmt":"2020-08-27T21:27:56","slug":"miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes","status":"publish","type":"ultimos_porgramas_po","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/","title":{"rendered":"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES"},"template":"","class_list":["post-366","ultimos_porgramas_po","type-ultimos_porgramas_po","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES - Direto ao Ponto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/\",\"name\":\"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2020-08-27T21:27:56+00:00\",\"dateModified\":\"2020-08-27T21:27:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00daltimos Programas\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/","og_locale":"pt_BR","og_type":"article","og_title":"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES - Direto ao Ponto","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/","og_site_name":"Direto ao Ponto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/","name":"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2020-08-27T21:27:56+00:00","dateModified":"2020-08-27T21:27:56+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/miguelzinho-capoeira-ao-vivo-no-atras-dos-bretes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"\u00daltimos Programas","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/"},{"@type":"ListItem","position":3,"name":"MIGUELZINHO CAPOEIRA AO VIVO NO ATR\u00c1S DOS BRETES"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po\/366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/ultimos_porgramas_po"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}