{"id":360,"date":"2020-08-20T17:54:14","date_gmt":"2020-08-20T20:54:14","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=ultimos_porgramas_po&#038;p=360"},"modified":"2020-08-20T17:56:08","modified_gmt":"2020-08-20T20:56:08","slug":"atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos","status":"publish","type":"ultimos_porgramas_po","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/","title":{"rendered":"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI &#8211; DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS"},"template":"","class_list":["post-360","ultimos_porgramas_po","type-ultimos_porgramas_po","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI - DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI - DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS - Direto ao Ponto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-20T20:56:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/\",\"name\":\"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI - DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2020-08-20T20:54:14+00:00\",\"dateModified\":\"2020-08-20T20:56:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00daltimos Programas\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI &#8211; DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI - DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/","og_locale":"pt_BR","og_type":"article","og_title":"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI - DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS - Direto ao Ponto","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/","og_site_name":"Direto ao Ponto","article_modified_time":"2020-08-20T20:56:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/","name":"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI - DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2020-08-20T20:54:14+00:00","dateModified":"2020-08-20T20:56:08+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-ao-vivo-com-jerominho-muzetti-direto-do-parque-do-peao-de-barretos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"\u00daltimos Programas","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/"},{"@type":"ListItem","position":3,"name":"ATR\u00c1S DOS BRETES AO VIVO COM JEROMINHO MUZETTI &#8211; DIRETO DO PARQUE DO PE\u00c3O DE BARRETOS"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/ultimos_porgramas_po"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}