{"id":342,"date":"2020-07-23T17:33:10","date_gmt":"2020-07-23T20:33:10","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=ultimos_porgramas_po&#038;p=342"},"modified":"2020-08-04T14:53:24","modified_gmt":"2020-08-04T17:53:24","slug":"atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo","status":"publish","type":"ultimos_porgramas_po","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/","title":{"rendered":"PAULO MULATO COUNTRY BULLS &#8211; AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO"},"template":"","class_list":["post-342","ultimos_porgramas_po","type-ultimos_porgramas_po","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PAULO MULATO COUNTRY BULLS - AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAULO MULATO COUNTRY BULLS - AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO - Direto ao Ponto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-04T17:53:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/\",\"name\":\"PAULO MULATO COUNTRY BULLS - AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2020-07-23T20:33:10+00:00\",\"dateModified\":\"2020-08-04T17:53:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00daltimos Programas\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PAULO MULATO COUNTRY BULLS &#8211; AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAULO MULATO COUNTRY BULLS - AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/","og_locale":"pt_BR","og_type":"article","og_title":"PAULO MULATO COUNTRY BULLS - AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO - Direto ao Ponto","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/","og_site_name":"Direto ao Ponto","article_modified_time":"2020-08-04T17:53:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/","name":"PAULO MULATO COUNTRY BULLS - AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2020-07-23T20:33:10+00:00","dateModified":"2020-08-04T17:53:24+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/atras-dos-bretes-com-paulo-mulato-country-bulls-ao-vivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"\u00daltimos Programas","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/"},{"@type":"ListItem","position":3,"name":"PAULO MULATO COUNTRY BULLS &#8211; AO VIVO NO ATRAS DOS BRETES COM JUJU CIZOTTO"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po\/342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/ultimos_porgramas_po"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}