{"id":2764,"date":"2024-02-29T16:41:19","date_gmt":"2024-02-29T19:41:19","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=ultimos_porgramas_po&#038;p=2764"},"modified":"2024-02-29T16:41:19","modified_gmt":"2024-02-29T19:41:19","slug":"ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp","status":"publish","type":"ultimos_porgramas_po","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","title":{"rendered":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da &#8211; ORINDI\u00daVA-SP"},"template":"","class_list":["post-2764","ultimos_porgramas_po","type-ultimos_porgramas_po","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\",\"name\":\"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2024-02-29T19:41:19+00:00\",\"dateModified\":\"2024-02-29T19:41:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00daltimos Programas\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da &#8211; ORINDI\u00daVA-SP\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","og_site_name":"Direto ao Ponto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","name":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2024-02-29T19:41:19+00:00","dateModified":"2024-02-29T19:41:19+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"\u00daltimos Programas","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/"},{"@type":"ListItem","position":3,"name":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da &#8211; ORINDI\u00daVA-SP"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po\/2764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/ultimos_porgramas_po"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=2764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}