{"id":2119,"date":"2023-02-16T17:22:09","date_gmt":"2023-02-16T20:22:09","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=ultimos_porgramas_po&#038;p=2119"},"modified":"2023-02-16T17:22:09","modified_gmt":"2023-02-16T20:22:09","slug":"ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023","status":"publish","type":"ultimos_porgramas_po","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/","title":{"rendered":"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O &#8211; 16\/02\/2023"},"template":"","class_list":["post-2119","ultimos_porgramas_po","type-ultimos_porgramas_po","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O - 16\/02\/2023 - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O - 16\/02\/2023 - Direto ao Ponto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/\",\"name\":\"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O - 16\/02\/2023 - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2023-02-16T20:22:09+00:00\",\"dateModified\":\"2023-02-16T20:22:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00daltimos Programas\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O &#8211; 16\/02\/2023\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O - 16\/02\/2023 - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/","og_locale":"pt_BR","og_type":"article","og_title":"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O - 16\/02\/2023 - Direto ao Ponto","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/","og_site_name":"Direto ao Ponto","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/","name":"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O - 16\/02\/2023 - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2023-02-16T20:22:09+00:00","dateModified":"2023-02-16T20:22:09+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/ao-vivo-atras-dos-bretes-com-sergio-expressao-16-02-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"\u00daltimos Programas","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/ultimos_porgramas_po\/"},{"@type":"ListItem","position":3,"name":"[AO VIVO] ATRAS DOS BRETES COM SERGIO EXPRESS\u00c3O &#8211; 16\/02\/2023"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po\/2119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/ultimos_porgramas_po"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/ultimos_porgramas_po"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=2119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}