{"id":2967,"date":"2024-07-19T08:46:02","date_gmt":"2024-07-19T11:46:02","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=galeria&#038;p=2967"},"modified":"2024-07-19T08:46:02","modified_gmt":"2024-07-19T11:46:02","slug":"ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto","status":"publish","type":"galeria","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/","title":{"rendered":"[AO VIVO] ATR\u00c1S DOS BRETES &#8211; FABIANO HAYASAKI | ARQUITETO"},"content":{"rendered":"<h3>Entrevista com o Arquiteto Fabiano Hayasaki no Programa &#8220;Atr\u00e1s dos Bretes&#8221;<\/h3>\n<p>Ontem, no programa &#8220;Atr\u00e1s dos Bretes&#8221;, tivemos o prazer de receber o arquiteto Fabiano Hayasaki. Ele compartilhou um pouco de sua trajet\u00f3ria antes de alcan\u00e7ar a fama e ser reconhecido como o melhor arquiteto da regi\u00e3o de S\u00e3o Jos\u00e9 do Rio Preto. Fabiano j\u00e1 conquistou v\u00e1rios pr\u00eamios na \u00e1rea da arquitetura e projetou casas para diversas celebridades, incluindo o renomado jogador de futebol Neymar.<\/p>\n<p>Foi uma conversa inspiradora, onde ele falou sobre os desafios e as conquistas ao longo de sua carreira. A dedica\u00e7\u00e3o e o talento de Fabiano s\u00e3o evidentes em cada um de seus projetos, refletindo inova\u00e7\u00e3o e excel\u00eancia em arquitetura.<\/p>\n<p>N\u00e3o perca a chance de conferir essa entrevista incr\u00edvel e conhecer mais sobre o trabalho de Fabiano Hayasaki!<\/p>\n","protected":false},"featured_media":2975,"template":"","class_list":["post-2967","galeria","type-galeria","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[AO VIVO] ATR\u00c1S DOS BRETES - FABIANO HAYASAKI | ARQUITETO - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[AO VIVO] ATR\u00c1S DOS BRETES - FABIANO HAYASAKI | ARQUITETO - Direto ao Ponto\" \/>\n<meta property=\"og:description\" content=\"Entrevista com o Arquiteto Fabiano Hayasaki no Programa &#8220;Atr\u00e1s dos Bretes&#8221; Ontem, no programa &#8220;Atr\u00e1s dos Bretes&#8221;, tivemos o prazer de receber o arquiteto Fabiano Hayasaki. Ele compartilhou um pouco de sua trajet\u00f3ria antes de alcan\u00e7ar a fama e ser reconhecido como o melhor arquiteto da regi\u00e3o de S\u00e3o Jos\u00e9 do Rio Preto. Fabiano j\u00e1&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-18-as-16.18.14_dafa1dcc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/\",\"name\":\"[AO VIVO] ATR\u00c1S DOS BRETES - FABIANO HAYASAKI | ARQUITETO - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2024-07-19T11:46:02+00:00\",\"dateModified\":\"2024-07-19T11:46:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerias\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[AO VIVO] ATR\u00c1S DOS BRETES &#8211; FABIANO HAYASAKI | ARQUITETO\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[AO VIVO] ATR\u00c1S DOS BRETES - FABIANO HAYASAKI | ARQUITETO - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/","og_locale":"pt_BR","og_type":"article","og_title":"[AO VIVO] ATR\u00c1S DOS BRETES - FABIANO HAYASAKI | ARQUITETO - Direto ao Ponto","og_description":"Entrevista com o Arquiteto Fabiano Hayasaki no Programa &#8220;Atr\u00e1s dos Bretes&#8221; Ontem, no programa &#8220;Atr\u00e1s dos Bretes&#8221;, tivemos o prazer de receber o arquiteto Fabiano Hayasaki. Ele compartilhou um pouco de sua trajet\u00f3ria antes de alcan\u00e7ar a fama e ser reconhecido como o melhor arquiteto da regi\u00e3o de S\u00e3o Jos\u00e9 do Rio Preto. Fabiano j\u00e1&hellip;","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/","og_site_name":"Direto ao Ponto","og_image":[{"width":1280,"height":720,"url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-18-as-16.18.14_dafa1dcc.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/","name":"[AO VIVO] ATR\u00c1S DOS BRETES - FABIANO HAYASAKI | ARQUITETO - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2024-07-19T11:46:02+00:00","dateModified":"2024-07-19T11:46:02+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-fabiano-hayasaki-arquiteto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"Galerias","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/"},{"@type":"ListItem","position":3,"name":"[AO VIVO] ATR\u00c1S DOS BRETES &#8211; FABIANO HAYASAKI | ARQUITETO"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/galeria\/2967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/galeria"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/galeria"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media\/2975"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=2967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}