{"id":2766,"date":"2024-02-29T16:48:46","date_gmt":"2024-02-29T19:48:46","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=galeria&#038;p=2766"},"modified":"2024-02-29T16:48:46","modified_gmt":"2024-02-29T19:48:46","slug":"ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp","status":"publish","type":"galeria","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","title":{"rendered":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da &#8211; ORINDI\u00daVA-SP"},"content":{"rendered":"<p>Oficialmente no fim da Piracema, Juju Cizotto n\u00e3o perdeu a grande abertura da pesca, mostrando tudo para n\u00f3s no Atr\u00e1s dos Bretes! Na pousada do Ja\u00fa em Orindi\u00fava, Juju fez o entretenimento dessa tarde. Assista ao programa no site!<\/p>\n","protected":false},"featured_media":2765,"template":"","class_list":["post-2766","galeria","type-galeria","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto\" \/>\n<meta property=\"og:description\" content=\"Oficialmente no fim da Piracema, Juju Cizotto n\u00e3o perdeu a grande abertura da pesca, mostrando tudo para n\u00f3s no Atr\u00e1s dos Bretes! Na pousada do Ja\u00fa em Orindi\u00fava, Juju fez o entretenimento dessa tarde. Assista ao programa no site!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-content\/uploads\/2024\/02\/ABERTURA-DA-PESCA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\",\"name\":\"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2024-02-29T19:48:46+00:00\",\"dateModified\":\"2024-02-29T19:48:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerias\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da &#8211; ORINDI\u00daVA-SP\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto","og_description":"Oficialmente no fim da Piracema, Juju Cizotto n\u00e3o perdeu a grande abertura da pesca, mostrando tudo para n\u00f3s no Atr\u00e1s dos Bretes! Na pousada do Ja\u00fa em Orindi\u00fava, Juju fez o entretenimento dessa tarde. Assista ao programa no site!","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","og_site_name":"Direto ao Ponto","og_image":[{"width":1280,"height":720,"url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-content\/uploads\/2024\/02\/ABERTURA-DA-PESCA.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/","name":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da - ORINDI\u00daVA-SP - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2024-02-29T19:48:46+00:00","dateModified":"2024-02-29T19:48:46+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/ao-vivo-atras-dos-bretes-com-mazola-na-pousada-do-jau-orindiuva-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"Galerias","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/"},{"@type":"ListItem","position":3,"name":"[AO VIVO] ATR\u00c1S DOS BRETES COM MAZOLA NA POUSADA DO JA\u00da &#8211; ORINDI\u00daVA-SP"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/galeria\/2766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/galeria"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/galeria"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media\/2765"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=2766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}