{"id":1038,"date":"2021-06-23T10:48:27","date_gmt":"2021-06-23T13:48:27","guid":{"rendered":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?post_type=galeria&#038;p=1038"},"modified":"2021-06-23T10:49:10","modified_gmt":"2021-06-23T13:49:10","slug":"juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia","status":"publish","type":"galeria","link":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/","title":{"rendered":"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA"},"content":{"rendered":"","protected":false},"featured_media":1043,"template":"","class_list":["post-1038","galeria","type-galeria","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA - Direto ao Ponto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA - Direto ao Ponto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/\" \/>\n<meta property=\"og:site_name\" content=\"Direto ao Ponto\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-23T13:49:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-content\/uploads\/2021\/06\/vMix-Capture-17-junho-2021-17-00-57.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\",\"name\":\"Direto ao Ponto\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/\",\"url\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/\",\"name\":\"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA - Direto ao Ponto\",\"isPartOf\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website\"},\"datePublished\":\"2021-06-23T13:48:27+00:00\",\"dateModified\":\"2021-06-23T13:49:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerias\",\"item\":\"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA - Direto ao Ponto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/","og_locale":"pt_BR","og_type":"article","og_title":"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA - Direto ao Ponto","og_url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/","og_site_name":"Direto ao Ponto","article_modified_time":"2021-06-23T13:49:10+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-content\/uploads\/2021\/06\/vMix-Capture-17-junho-2021-17-00-57.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/","name":"Direto ao Ponto","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arenacp.com.br\/direto-ao-ponto\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/","url":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/","name":"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA - Direto ao Ponto","isPartOf":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/#website"},"datePublished":"2021-06-23T13:48:27+00:00","dateModified":"2021-06-23T13:49:10+00:00","breadcrumb":{"@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/juju-cizotto-marina-fabris-apresentando-a-festa-junina-da-apae-de-olimpia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/"},{"@type":"ListItem","position":2,"name":"Galerias","item":"https:\/\/arenacp.com.br\/direto-ao-ponto\/galeria\/"},{"@type":"ListItem","position":3,"name":"JUJU CIZOTTO | MARINA FABRIS | APRESENTANDO A FESTA JUNINA DA APAE DE OLIMPIA"}]}]}},"_links":{"self":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/galeria\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/galeria"}],"about":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/types\/galeria"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media\/1043"}],"wp:attachment":[{"href":"https:\/\/arenacp.com.br\/direto-ao-ponto\/wp-json\/wp\/v2\/media?parent=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}